{"id":1612,"count":1,"description":"","link":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/autor\/gilda-collo\/","name":"Gilda Collo","slug":"gilda-collo","taxonomy":"autor","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/autor\/1612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/autor"}],"about":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/taxonomies\/autor"}],"wp:post_type":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/product?autor=1612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}