{"id":228,"count":6,"description":"","link":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/autor\/leticia-paz-sena\/","name":"Leticia Paz Sena","slug":"leticia-paz-sena","taxonomy":"autor","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/autor\/228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/autor"}],"about":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/taxonomies\/autor"}],"wp:post_type":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/product?autor=228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}