{"id":2970,"count":1,"description":"","link":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/autor\/ricardo-sanmartin\/","name":"Ricardo Sanmart\u00edn","slug":"ricardo-sanmartin","taxonomy":"autor","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/autor\/2970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/autor"}],"about":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/taxonomies\/autor"}],"wp:post_type":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/product?autor=2970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}