{"id":1422,"count":1,"description":"","link":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/compilador\/sofia-ambrogi\/","name":"Sof\u00eda Ambrogi","slug":"sofia-ambrogi","taxonomy":"compilador","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/compilador\/1422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/compilador"}],"about":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/taxonomies\/compilador"}],"wp:post_type":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/product?compilador=1422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}