{"id":2535,"count":1,"description":"","link":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/compilador\/jose-nicolas-gerez-cuevas\/","name":"Jos\u00e9 Nicol\u00e1s Gerez Cuevas","slug":"jose-nicolas-gerez-cuevas","taxonomy":"compilador","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/compilador\/2535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/compilador"}],"about":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/taxonomies\/compilador"}],"wp:post_type":[{"href":"https:\/\/ffyh.unc.edu.ar\/publicaciones\/wp-json\/wp\/v2\/product?compilador=2535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}